{"id":5177,"date":"2013-11-22T13:01:50","date_gmt":"2013-11-22T12:01:50","guid":{"rendered":"https:\/\/fr.blogs.cam4.com\/?p=5177"},"modified":"2013-11-26T11:44:57","modified_gmt":"2013-11-26T10:44:57","slug":"tournage-dun-film-amateur-x-en-live-webcam-gratuite-sur-cam4","status":"publish","type":"post","link":"https:\/\/fr.cam4.com\/blog\/camgirls\/tournage-dun-film-amateur-x-en-live-webcam-gratuite-sur-cam4\/","title":{"rendered":"Tournage d&#8217;un film Amateur X en live Webcam Gratuite sur Cam4"},"content":{"rendered":"<p>1 er tournage d&#8217;un film amateur X en live sur <a href=\"https:\/\/fr.cam4.com\/lsftv\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.cam4.fr\/lsftv<\/a> avec Elisa &amp; Sebastien ( Un jeune couple qui ont contact\u00e9 <a href=\"https:\/\/lsfradio.com\/v2\/libre-antenne-speciale-casting-x-avec-elisa-sebastien\/\">LSF Radio <\/a>pour leur <a href=\"https:\/\/lsfradio.com\/v2\/casting-porno-amateur-lsf-radio\/\">CASTING X<\/a> ) Elisa est italienne quand \u00e0 Sebastien lui il est Francais. Adepte de sexe sans tabou et avide de sensations forte ce jeune couple sera \u00e0 bord du van de Pipi et Gogo dans PARIS pour leur casting X en live et en duplex radio <a href=\"https:\/\/www.facebook.com\/hashtag\/lsfradio?source=embed\" target=\"_blank\">\u202a#\u200eLSFRADIO\u202c<\/a> \u00e0 ne pas manquer LUNDI 25 NOVEMBRE 15H-18H<\/p>\n<p>LSF RADIO et Cam4 vous offrent des duplex in\u00e9dit entre le studio de la radio et le Van de Pipi &amp; Gogo qui d\u00e9buteront le tournage en plein coeur de PARIS avant leurs arriv\u00e9es au Studio pour une interviews X et des interactions des auditeurs en live. Noss Gor et Pilou Gornoss.<\/p>\n<div id=\"stcpDiv\">\n<p>\u00a0Un seul Numero pour participer et r\u00e9agir en direct Avoir les 1 ere impression \u00e0 chaud de Am\u00e9lie ENVOYEZ ANTENNE \/SMS 06 25 24 91 90 ( Non Surtax\u00e9 ) On vous rappelera pendant l\u2019\u00e9mission en direct ( D\u00e9crocher votre tel on sera en N\u00b0 masqu\u00e9 ).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 er tournage d&#8217;un film amateur X en live sur <a href=\"https:\/\/fr.cam4.com\/lsftv\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.cam4.fr\/lsftv<\/a> avec Elisa &amp; Sebastien ( Un jeune couple qui<\/p>\n","protected":false},"author":6,"featured_media":5178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[37128,37134],"tags":[37157,40201,37144,32484,35863],"_links":{"self":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/5177"}],"collection":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=5177"}],"version-history":[{"count":0,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/5177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/media\/5178"}],"wp:attachment":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/media?parent=5177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/categories?post=5177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/tags?post=5177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}