{"id":33954,"date":"2021-06-24T16:40:32","date_gmt":"2021-06-24T14:40:32","guid":{"rendered":"https:\/\/www.cam4.fr\/blog\/?p=33954"},"modified":"2021-06-30T14:07:05","modified_gmt":"2021-06-30T12:07:05","slug":"covid-19-les-hommes-pensent-plus-au-sexe-cet-ete-etonnant","status":"publish","type":"post","link":"https:\/\/fr.cam4.com\/blog\/2-blog\/covid-19-les-hommes-pensent-plus-au-sexe-cet-ete-etonnant\/","title":{"rendered":"Covid-19 : les hommes pensent plus au sexe cet \u00e9t\u00e9, \u00e9tonnant ?"},"content":{"rendered":"\n<p><strong>Cet \u00e9t\u00e9, les hommes vont renouveler leur activit\u00e9 sexuelle, laissant (presque) loin derri\u00e8re la covid-19. Une envie qui en dit long sur les diff\u00e9rents penchants qu\u2019ils ont\u2026<\/strong><\/p>\n\n\n\n<p><em>\u00ab Lib\u00e9r\u00e9, d\u00e9livr\u00e9\u2026 \u00bb. <\/em>C\u2019est peu dire que de crier haut et fort cet hymne de l&#8217;h\u00e9ro\u00efne est l\u00e9gitime, en cette p\u00e9riode anxiog\u00e8ne. Selon la nouvelle \u00e9tude IFOP\/<a rel=\"noreferrer noopener\" href=\"https:\/\/www.cam4.fr\/homme\" target=\"_blank\">CAM4<\/a>, les Fran\u00e7ais entendent reprendre pleinement leurs anciennes habitudes dans le contexte de Covid-19. En cause, 46% des hommes c\u00e9libataires envisagent des relations plus ouvertes avec leur(s) partenaire(s). \u00ab <em>Chez les moins de 25 ans (pour 44% d\u2019entre eux), ce \u00ab gender gap \u00bb se retrouve dans toutes les situations test\u00e9es : 43% des jeunes adultes (de sexe masculin) annoncent notamment qu\u2019ils sont dispos\u00e9s \u00e0 faire l\u2019amour sans sentiments. \u00bb, <\/em>stipule l\u2019enqu\u00eate.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image5.jpeg\"><img loading=\"lazy\" width=\"605\" height=\"366\" src=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image5.jpeg\" alt=\"\" data-id=\"33956\" data-full-url=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image5.jpeg\" data-link=\"https:\/\/www.cam4.fr\/blog\/?attachment_id=33956\" class=\"wp-image-33956\" srcset=\"https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image5.jpeg 605w, https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image5-300x181.jpeg 300w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image4.png\"><img loading=\"lazy\" width=\"572\" height=\"379\" src=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image4.png\" alt=\"\" class=\"wp-image-33958\" srcset=\"https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image4.png 572w, https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image4-300x199.png 300w\" sizes=\"(max-width: 572px) 100vw, 572px\" \/><\/a><\/figure>\n\n\n\n<p>Pr\u00e9cis\u00e9ment, les hommes vont \u00eatre 30% \u00e0 vouloir aborder cette question dans des \u00e9changes, 28% souhaiteront passer \u00e0 l\u2019acte plut\u00f4t que de discuter. En cons\u00e9quence, 34% d\u2019entre vont c\u00e9der davantage aux avances d\u2019une personne, amenant ainsi \u00e0 une aventure sans lendemain. L\u2019ouverture devient plus importante pour ceux qui sont homosexuels, puisque 68% d\u2019entre eux se disent pr\u00eats \u00e0 op\u00e9rer de cette mani\u00e8re. Ce qui promet d\u2019\u00eatre vraiment chaud tous les soirs d\u2019\u00e9t\u00e9, ne pensez-vous pas ?<\/p>\n\n\n\n<p><strong>Une pratique bien pr\u00e9sente<\/strong><\/p>\n\n\n\n<p>Toujours dans le sondage, les hommes c\u00e9libataires, homos et bi, sont 34% et 30% \u00e0 esp\u00e9rer multiplier les partenaires. Et ce, alors qu\u2019ils y avaient recours pendant la pand\u00e9mie. <em>\u00ab<a href=\"https:\/\/www.cam4.fr\/blog\/actualites\/le-foda-le-nouveau-mal-des-celibataires-covid-19\/\"> Signe des difficult\u00e9s \u00e0 faire des rencontres autant qu\u2019\u00e0 prendre des risques avec des inconnus, la plupart en ont eu avec une personne avec laquelle ils avaient d\u00e9j\u00e0 eu des relations sexuelles. <\/a>\u00bb<\/em>, peut-on y lire.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image2.jpeg\"><img loading=\"lazy\" width=\"622\" height=\"393\" src=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image2.jpeg\" alt=\"\" data-id=\"33959\" data-link=\"https:\/\/www.cam4.fr\/blog\/?attachment_id=33959\" class=\"wp-image-33959\" srcset=\"https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image2.jpeg 622w, https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image2-300x190.jpeg 300w\" sizes=\"(max-width: 622px) 100vw, 622px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image3.png\"><img loading=\"lazy\" width=\"680\" height=\"373\" src=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image3.png\" alt=\"\" data-id=\"33960\" data-full-url=\"https:\/\/www.cam4.fr\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image3.png\" data-link=\"https:\/\/www.cam4.fr\/blog\/?attachment_id=33960\" class=\"wp-image-33960\" srcset=\"https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image3.png 680w, https:\/\/fr.cam4.com\/blog\/wp-content\/blogs.dir\/5\/files\/2021\/06\/Image3-300x165.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Pour autant, la gent masculine n\u2019a pas perdu de vue la vie sentimentale. En effet, 37% des hommes disent avoir repris contact avec un de leurs pairs qu\u2019ils avaient c\u00f4toy\u00e9 au cours de la pand\u00e9mie. \u00c0 contrario, 33% des sond\u00e9s ont encha\u00een\u00e9 les plans entre janvier 2020 et aujourd\u2019hui. \u00ab<a href=\"https:\/\/www.cam4.fr\/blog\/actualites\/le-foda-le-nouveau-mal-des-celibataires-covid-19\/\"> <em>la phase de sortie du troisi\u00e8me confinement n\u2019a pas pouss\u00e9 tous les c\u00e9libataires fran\u00e7ais \u00e0 la \u00ab boulimie \u00bb de partenaires qu\u2019aurait pu susciter le besoin de rattraper les mois de \u00ab disette sexuelle \u00bb impos\u00e9e par la crise sanitaire. <\/em><\/a><em>\u00bb, <\/em>conclut l\u2019enqu\u00eate.<\/p>\n\n\n\n<h4><strong>Plus d\u2019infos :&nbsp;<\/strong><\/h4>\n\n\n\n<p>D\u00e9couvrez l\u2019int\u00e9gralit\u00e9 de l\u2019enqu\u00eate sur &#8220;le summer of love&#8221; en temps de covid-19 sur le site de l\u2019<a rel=\"noreferrer noopener\" href=\"https:\/\/www.ifop.com\/\" target=\"_blank\">IFOP<\/a>.\u00a0<\/p>\n\n\n\n<p><strong>Suivez-nous sur\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCaTVa8OizOXUHZdOCe8p_mQ\">Youtube<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/cam4?lang=en\">Twitter<\/a>\u00a0,\u00a0<a href=\"https:\/\/www.instagram.com\/cam4_francais\/\">Instagram<\/a>\u00a0et\u00a0<a href=\"https:\/\/www.facebook.com\/pg\/Cam4france-1203743733091252\/posts\/?ref=page_internal\">Facebook<\/a>\u00a0pour recevoir toutes les actualit\u00e9s du monde de CAM4!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cet \u00e9t\u00e9, les hommes vont renouveler leur activit\u00e9 sexuelle, laissant (presque) loin derri\u00e8re la covid-19. Une envie qui en dit long sur les<\/p>\n","protected":false},"author":1,"featured_media":33955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[32044,37129],"tags":[],"_links":{"self":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/33954"}],"collection":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=33954"}],"version-history":[{"count":3,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/33954\/revisions"}],"predecessor-version":[{"id":34025,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/33954\/revisions\/34025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/media\/33955"}],"wp:attachment":[{"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/media?parent=33954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/categories?post=33954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.cam4.com\/blog\/wp-json\/wp\/v2\/tags?post=33954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}